{"id":2171,"date":"2025-11-04T08:51:50","date_gmt":"2025-11-04T08:51:50","guid":{"rendered":"https:\/\/vaderkleinjan.nl\/unbegrenzt-spareribs-deal\/"},"modified":"2026-04-10T06:50:22","modified_gmt":"2026-04-10T06:50:22","slug":"unbegrenzt-spareribs-deal","status":"publish","type":"post","link":"https:\/\/vaderkleinjan.nl\/de\/unbegrenzt-spareribs-deal\/","title":{"rendered":"Unbegrenzt Spareribs Deal"},"content":{"rendered":"\n<p>Kommen Sie und genie\u00dfen Sie unsere k\u00f6stlichen unbegrenzten Spareribs &#8211; zart, perfekt gegart und serviert mit Pommes frites, Salat und verschiedenen So\u00dfen.<br\/>Ideal f\u00fcr echte Fleischliebhaber&#8230; essen Sie so viel Sie wollen! Sonntag und Montag f\u00fcr \u20ac23.50<\/p>\n\n<p>Enddatum: Feb 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kommen Sie und genie\u00dfen Sie unsere k\u00f6stlichen unbegrenzten Spareribs &#8211; zart, perfekt gegart und serviert mit Pommes frites, Salat und verschiedenen So\u00dfen.Ideal f\u00fcr echte Fleischliebhaber&#8230; essen Sie so viel Sie wollen! Sonntag und Montag f\u00fcr \u20ac23.50 Enddatum: Feb 2026<\/p>\n","protected":false},"author":2,"featured_media":2197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-2171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deal"],"_links":{"self":[{"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/posts\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":3,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/posts\/2171\/revisions"}],"predecessor-version":[{"id":2360,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/posts\/2171\/revisions\/2360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/media?parent=2171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/categories?post=2171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaderkleinjan.nl\/de\/wp-json\/wp\/v2\/tags?post=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}